{"id":18146,"date":"2026-02-10T17:53:57","date_gmt":"2026-02-10T17:53:57","guid":{"rendered":"https:\/\/lab.festivalcapuchos.com\/?p=18146"},"modified":"2026-03-26T17:41:52","modified_gmt":"2026-03-26T17:41:52","slug":"masterclasses-dos-capuchos-3","status":"publish","type":"post","link":"https:\/\/lab.festivalcapuchos.com\/en\/masterclasses-dos-capuchos-3\/","title":{"rendered":"Capuchos Masterclasses"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ocean_front_end_style_editor":"no","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[30,27,38,64,40,46],"tags":[],"ano":[85,32],"concerto-com-pagina":[],"class_list":["post-18146","post","type-post","status-publish","format-standard","hentry","category-ano-em-curso","category-calendario","category-masterclass","category-o-festival","category-preludios-masterclass-caminhada","category-programa-geral","ano-85","ano-corrente","entry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Andreia Carvalho\"\/>\n\t<meta name=\"google-site-verification\" content=\"sy1uYlrwItWeoGZgdRBBrgERAURdM1NZLTjfn6Ou-sw\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/lab.festivalcapuchos.com\/en\/masterclasses-dos-capuchos-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Festival de M\u00fasica dos Capuchos - Official site\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Masterclasses dos Capuchos - Festival de M\u00fasica dos Capuchos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/lab.festivalcapuchos.com\/en\/masterclasses-dos-capuchos-3\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/GERAL-1X1-REDES.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/GERAL-1X1-REDES.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-02-10T17:53:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-03-26T17:41:52+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/festivalcapuchos\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Masterclasses dos Capuchos - Festival de M\u00fasica dos Capuchos\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/GERAL-1X1-REDES.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/masterclasses-dos-capuchos-3\\\/#blogposting\",\"name\":\"Masterclasses dos Capuchos - Festival de M\\u00fasica dos Capuchos\",\"headline\":\"Masterclasses dos Capuchos\",\"author\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/author\\\/andreia\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/festivalcapuchos.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Flavicon-Capuchos-2025.png\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/#articleImage\"},\"datePublished\":\"2026-02-10T17:53:57+00:00\",\"dateModified\":\"2026-03-26T17:41:52+00:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/masterclasses-dos-capuchos-3\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/masterclasses-dos-capuchos-3\\\/#webpage\"},\"articleSection\":\"Ano em curso, Calend\\u00e1rio, Masterclass, O Festival, Outras Actividades, Programa Geral, 2026, Corrente\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/masterclasses-dos-capuchos-3\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/category\\\/o-festival\\\/#listItem\",\"name\":\"O Festival\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/category\\\/o-festival\\\/#listItem\",\"position\":2,\"name\":\"O Festival\",\"item\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/category\\\/o-festival\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/category\\\/o-festival\\\/preludios-masterclass-caminhada\\\/#listItem\",\"name\":\"Outras Actividades\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/category\\\/o-festival\\\/preludios-masterclass-caminhada\\\/#listItem\",\"position\":3,\"name\":\"Outras Actividades\",\"item\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/category\\\/o-festival\\\/preludios-masterclass-caminhada\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/category\\\/o-festival\\\/preludios-masterclass-caminhada\\\/masterclass\\\/#listItem\",\"name\":\"Masterclass\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/category\\\/o-festival\\\/#listItem\",\"name\":\"O Festival\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/category\\\/o-festival\\\/preludios-masterclass-caminhada\\\/masterclass\\\/#listItem\",\"position\":4,\"name\":\"Masterclass\",\"item\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/category\\\/o-festival\\\/preludios-masterclass-caminhada\\\/masterclass\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/masterclasses-dos-capuchos-3\\\/#listItem\",\"name\":\"Masterclasses dos Capuchos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/category\\\/o-festival\\\/preludios-masterclass-caminhada\\\/#listItem\",\"name\":\"Outras Actividades\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/masterclasses-dos-capuchos-3\\\/#listItem\",\"position\":5,\"name\":\"Masterclasses dos Capuchos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/category\\\/o-festival\\\/preludios-masterclass-caminhada\\\/masterclass\\\/#listItem\",\"name\":\"Masterclass\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/#organization\",\"name\":\"Festival de M\\u00fasica dos Capuchos\",\"description\":\"Official site\",\"url\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/festivalcapuchos.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Flavicon-Capuchos-2025.png\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/masterclasses-dos-capuchos-3\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/masterclasses-dos-capuchos-3\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/festivalcapuchos\",\"https:\\\/\\\/instagram.com\\\/festivalcapuchos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/author\\\/andreia\\\/#author\",\"url\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/author\\\/andreia\\\/\",\"name\":\"Andreia Carvalho\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/masterclasses-dos-capuchos-3\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a3774dc8b5a026cbec06b0604d85ba7ef878d102271d1830a9acffd0df4bf29?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Andreia Carvalho\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/masterclasses-dos-capuchos-3\\\/#webpage\",\"url\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/masterclasses-dos-capuchos-3\\\/\",\"name\":\"Masterclasses dos Capuchos - Festival de M\\u00fasica dos Capuchos\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/masterclasses-dos-capuchos-3\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/author\\\/andreia\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/author\\\/andreia\\\/#author\"},\"datePublished\":\"2026-02-10T17:53:57+00:00\",\"dateModified\":\"2026-03-26T17:41:52+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/\",\"name\":\"Festival de M\\u00fasica dos Capuchos\",\"description\":\"Official site\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Masterclasses dos Capuchos - Festival de M\u00fasica dos Capuchos","description":"","canonical_url":"https:\/\/lab.festivalcapuchos.com\/en\/masterclasses-dos-capuchos-3\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"sy1uYlrwItWeoGZgdRBBrgERAURdM1NZLTjfn6Ou-sw","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/lab.festivalcapuchos.com\/en\/masterclasses-dos-capuchos-3\/#blogposting","name":"Masterclasses dos Capuchos - Festival de M\u00fasica dos Capuchos","headline":"Masterclasses dos Capuchos","author":{"@id":"https:\/\/lab.festivalcapuchos.com\/en\/author\/andreia\/#author"},"publisher":{"@id":"https:\/\/lab.festivalcapuchos.com\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/Flavicon-Capuchos-2025.png","@id":"https:\/\/lab.festivalcapuchos.com\/en\/#articleImage"},"datePublished":"2026-02-10T17:53:57+00:00","dateModified":"2026-03-26T17:41:52+00:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/lab.festivalcapuchos.com\/en\/masterclasses-dos-capuchos-3\/#webpage"},"isPartOf":{"@id":"https:\/\/lab.festivalcapuchos.com\/en\/masterclasses-dos-capuchos-3\/#webpage"},"articleSection":"Ano em curso, Calend\u00e1rio, Masterclass, O Festival, Outras Actividades, Programa Geral, 2026, Corrente"},{"@type":"BreadcrumbList","@id":"https:\/\/lab.festivalcapuchos.com\/en\/masterclasses-dos-capuchos-3\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/lab.festivalcapuchos.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/en\/category\/o-festival\/#listItem","name":"O Festival"}},{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/en\/category\/o-festival\/#listItem","position":2,"name":"O Festival","item":"https:\/\/lab.festivalcapuchos.com\/en\/category\/o-festival\/","nextItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/en\/category\/o-festival\/preludios-masterclass-caminhada\/#listItem","name":"Outras Actividades"},"previousItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/en\/category\/o-festival\/preludios-masterclass-caminhada\/#listItem","position":3,"name":"Outras Actividades","item":"https:\/\/lab.festivalcapuchos.com\/en\/category\/o-festival\/preludios-masterclass-caminhada\/","nextItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/en\/category\/o-festival\/preludios-masterclass-caminhada\/masterclass\/#listItem","name":"Masterclass"},"previousItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/en\/category\/o-festival\/#listItem","name":"O Festival"}},{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/en\/category\/o-festival\/preludios-masterclass-caminhada\/masterclass\/#listItem","position":4,"name":"Masterclass","item":"https:\/\/lab.festivalcapuchos.com\/en\/category\/o-festival\/preludios-masterclass-caminhada\/masterclass\/","nextItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/en\/masterclasses-dos-capuchos-3\/#listItem","name":"Masterclasses dos Capuchos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/en\/category\/o-festival\/preludios-masterclass-caminhada\/#listItem","name":"Outras Actividades"}},{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/en\/masterclasses-dos-capuchos-3\/#listItem","position":5,"name":"Masterclasses dos Capuchos","previousItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/en\/category\/o-festival\/preludios-masterclass-caminhada\/masterclass\/#listItem","name":"Masterclass"}}]},{"@type":"Organization","@id":"https:\/\/lab.festivalcapuchos.com\/en\/#organization","name":"Festival de M\u00fasica dos Capuchos","description":"Official site","url":"https:\/\/lab.festivalcapuchos.com\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/Flavicon-Capuchos-2025.png","@id":"https:\/\/lab.festivalcapuchos.com\/en\/masterclasses-dos-capuchos-3\/#organizationLogo"},"image":{"@id":"https:\/\/lab.festivalcapuchos.com\/en\/masterclasses-dos-capuchos-3\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/festivalcapuchos","https:\/\/instagram.com\/festivalcapuchos"]},{"@type":"Person","@id":"https:\/\/lab.festivalcapuchos.com\/en\/author\/andreia\/#author","url":"https:\/\/lab.festivalcapuchos.com\/en\/author\/andreia\/","name":"Andreia Carvalho","image":{"@type":"ImageObject","@id":"https:\/\/lab.festivalcapuchos.com\/en\/masterclasses-dos-capuchos-3\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4a3774dc8b5a026cbec06b0604d85ba7ef878d102271d1830a9acffd0df4bf29?s=96&d=mm&r=g","width":96,"height":96,"caption":"Andreia Carvalho"}},{"@type":"WebPage","@id":"https:\/\/lab.festivalcapuchos.com\/en\/masterclasses-dos-capuchos-3\/#webpage","url":"https:\/\/lab.festivalcapuchos.com\/en\/masterclasses-dos-capuchos-3\/","name":"Masterclasses dos Capuchos - Festival de M\u00fasica dos Capuchos","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/lab.festivalcapuchos.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/lab.festivalcapuchos.com\/en\/masterclasses-dos-capuchos-3\/#breadcrumblist"},"author":{"@id":"https:\/\/lab.festivalcapuchos.com\/en\/author\/andreia\/#author"},"creator":{"@id":"https:\/\/lab.festivalcapuchos.com\/en\/author\/andreia\/#author"},"datePublished":"2026-02-10T17:53:57+00:00","dateModified":"2026-03-26T17:41:52+00:00"},{"@type":"WebSite","@id":"https:\/\/lab.festivalcapuchos.com\/en\/#website","url":"https:\/\/lab.festivalcapuchos.com\/en\/","name":"Festival de M\u00fasica dos Capuchos","description":"Official site","inLanguage":"en-US","publisher":{"@id":"https:\/\/lab.festivalcapuchos.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Festival de M\u00fasica dos Capuchos - Official site","og:type":"article","og:title":"Masterclasses dos Capuchos - Festival de M\u00fasica dos Capuchos","og:url":"https:\/\/lab.festivalcapuchos.com\/en\/masterclasses-dos-capuchos-3\/","og:image":"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/GERAL-1X1-REDES.jpg","og:image:secure_url":"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/GERAL-1X1-REDES.jpg","article:published_time":"2026-02-10T17:53:57+00:00","article:modified_time":"2026-03-26T17:41:52+00:00","article:publisher":"https:\/\/facebook.com\/festivalcapuchos","twitter:card":"summary","twitter:title":"Masterclasses dos Capuchos - Festival de M\u00fasica dos Capuchos","twitter:image":"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/GERAL-1X1-REDES.jpg"},"aioseo_meta_data":{"post_id":"18146","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-02-10 17:48:34","updated":"2026-03-26 18:26:32","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lab.festivalcapuchos.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lab.festivalcapuchos.com\/en\/category\/o-festival\/\" title=\"O Festival\">O Festival<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lab.festivalcapuchos.com\/en\/category\/o-festival\/preludios-masterclass-caminhada\/\" title=\"Outras Actividades\">Outras Actividades<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lab.festivalcapuchos.com\/en\/category\/o-festival\/preludios-masterclass-caminhada\/masterclass\/\" title=\"Masterclass\">Masterclass<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMasterclasses dos Capuchos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/lab.festivalcapuchos.com\/en"},{"label":"O Festival","link":"https:\/\/lab.festivalcapuchos.com\/en\/category\/o-festival\/"},{"label":"Outras Actividades","link":"https:\/\/lab.festivalcapuchos.com\/en\/category\/o-festival\/preludios-masterclass-caminhada\/"},{"label":"Masterclass","link":"https:\/\/lab.festivalcapuchos.com\/en\/category\/o-festival\/preludios-masterclass-caminhada\/masterclass\/"},{"label":"Masterclasses dos Capuchos","link":"https:\/\/lab.festivalcapuchos.com\/en\/masterclasses-dos-capuchos-3\/"}],"_links":{"self":[{"href":"https:\/\/lab.festivalcapuchos.com\/en\/wp-json\/wp\/v2\/posts\/18146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lab.festivalcapuchos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lab.festivalcapuchos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lab.festivalcapuchos.com\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/lab.festivalcapuchos.com\/en\/wp-json\/wp\/v2\/comments?post=18146"}],"version-history":[{"count":5,"href":"https:\/\/lab.festivalcapuchos.com\/en\/wp-json\/wp\/v2\/posts\/18146\/revisions"}],"predecessor-version":[{"id":18602,"href":"https:\/\/lab.festivalcapuchos.com\/en\/wp-json\/wp\/v2\/posts\/18146\/revisions\/18602"}],"wp:attachment":[{"href":"https:\/\/lab.festivalcapuchos.com\/en\/wp-json\/wp\/v2\/media?parent=18146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lab.festivalcapuchos.com\/en\/wp-json\/wp\/v2\/categories?post=18146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lab.festivalcapuchos.com\/en\/wp-json\/wp\/v2\/tags?post=18146"},{"taxonomy":"ano","embeddable":true,"href":"https:\/\/lab.festivalcapuchos.com\/en\/wp-json\/wp\/v2\/ano?post=18146"},{"taxonomy":"concerto-com-pagina","embeddable":true,"href":"https:\/\/lab.festivalcapuchos.com\/en\/wp-json\/wp\/v2\/concerto-com-pagina?post=18146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}