{"id":16855,"date":"2025-03-28T10:23:50","date_gmt":"2025-03-28T10:23:50","guid":{"rendered":"https:\/\/lab.festivalcapuchos.com\/?post_type=artista&#038;p=16855"},"modified":"2025-04-30T17:34:55","modified_gmt":"2025-04-30T16:34:55","slug":"yulia-deyneka","status":"publish","type":"artista","link":"https:\/\/lab.festivalcapuchos.com\/pt\/artista\/yulia-deyneka\/","title":{"rendered":"Yulia Deyneka"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nascida na R\u00fassia, em 1982, Yulia Deyneka estudou com Alexander Bobrovsky no Conservat\u00f3rio Tchaikovsky da sua cidade natal, Moscovo. Em 2001, mudou-se para a Alemanha, onde se diplomou pela Universidade de M\u00fasica e Teatro de Rostock, sob a orienta\u00e7\u00e3o de Felix Schwartz, tendo posteriormente obtido o Diploma de Solista na Universidade das Artes de Berlim, com Wilfried Strehle. Ainda enquanto estudante, foi-lhe atribu\u00edda a posi\u00e7\u00e3o de Viola Solo na prestigiada Orquestra Staatskapelle de Berlim.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como solista, tocou com maestros de renome como Andris Nelsons, Fran\u00e7ois-Xavier Roth, Zubin Mehta e Daniel Barenboim, apresentando-se em salas de prest\u00edgio como o Carnegie Hall, em Nova Iorque, e as Philharmonie de Berlim e de Paris.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A m\u00fasica de c\u00e2mara ocupa um lugar de destaque na vida de Yulia Deyneka. \u00c9 presen\u00e7a regular em in\u00fameros festivais internacionais, entre os quais se contam Rolandseck, Jerusal\u00e9m, Annecy e Mozart de Salzburgo. Entre os seus parceiros musicais contam-se Guy Braunstein, Daniel Ottensamer, Emmanuel Pahud, Julian Steckel e J\u00f6rg Widmann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yulia Deyneka \u00e9 co-fundadora do Quarteto de Cordas da Staatskapelle de Berlim. Na inaugura\u00e7\u00e3o da Pierre Boulez Saal, o ensemble interpretou a integral dos quartetos de cordas de Schubert, e desde ent\u00e3o tem-se apresentado internacionalmente ao lado de grandes nomes como Elisabeth Leonskaja, Frans Helmerson e Christiane Karg.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada vez mais empenhada na m\u00fasica contempor\u00e2nea, Yulia Deyneka integra desde a sua funda\u00e7\u00e3o o Boulez Ensemble, com o qual estreou obras de in\u00fameros compositores vivos, entre eles Aribert Reimann, J\u00f6rg Widmann, Olga Neuwirth, Johannes Borowski e Matthias Pintscher.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mant\u00e9m uma duradoura parceria musical em m\u00fasica de c\u00e2mara com Daniel Barenboim, com quem tamb\u00e9m colabora na West-Eastern Divan Orchestra. Desde 2003, lidera a sec\u00e7\u00e3o de violas desta orquestra, estando activamente envolvida na forma\u00e7\u00e3o de jovens talentos oriundos do M\u00e9dio Oriente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na Staatskapelle de Berlim, exerce ainda o papel de mentora dos jovens violetistas da Academia da orquestra.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde 2016, lecciona na Academia Barenboim-Said de Berlim, onde iniciou fun\u00e7\u00f5es como Professora Catedr\u00e1tica em 2019.Yulia Deyneka pode ser ouvida no \u00e1lbum <em>Soir\u00e9e<\/em> (Pentatone), com Magdalena Ko\u017een\u00e1 e Simon Rattle, e no \u00e1lbum da integral dos quartetos com piano de Mozart (Deutsche Grammophon), ao lado de Michael Barenboim, Kian Soltani e Daniel Barenboim.<\/p>\n","protected":false},"featured_media":16160,"template":"","categories":[58,30,41,46],"ano":[17,32],"com-pagina":[65],"class_list":["post-16855","artista","type-artista","status-publish","has-post-thumbnail","hentry","category-20-junho","category-ano-em-curso","category-pagina_artistas","category-programa-geral","ano-17","ano-corrente","com-pagina-sim","entry","has-media"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Nascida na R\u00fassia, em 1982, Yulia Deyneka estudou com Alexander Bobrovsky no Conservat\u00f3rio Tchaikovsky da sua cidade natal, Moscovo. Em 2001, mudou-se para a Alemanha, onde se diplomou pela Universidade de M\u00fasica e Teatro de Rostock, sob a orienta\u00e7\u00e3o de Felix Schwartz, tendo posteriormente obtido o Diploma de Solista na Universidade das Artes de Berlim,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"sy1uYlrwItWeoGZgdRBBrgERAURdM1NZLTjfn6Ou-sw\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/lab.festivalcapuchos.com\/pt\/artista\/yulia-deyneka\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_PT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Festival de M\u00fasica dos Capuchos - Official site\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Yulia Deyneka - Festival de M\u00fasica dos Capuchos\" \/>\n\t\t<meta property=\"og:description\" content=\"Nascida na R\u00fassia, em 1982, Yulia Deyneka estudou com Alexander Bobrovsky no Conservat\u00f3rio Tchaikovsky da sua cidade natal, Moscovo. Em 2001, mudou-se para a Alemanha, onde se diplomou pela Universidade de M\u00fasica e Teatro de Rostock, sob a orienta\u00e7\u00e3o de Felix Schwartz, tendo posteriormente obtido o Diploma de Solista na Universidade das Artes de Berlim,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/lab.festivalcapuchos.com\/pt\/artista\/yulia-deyneka\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/Yulia-Deyneka-by-Zuzana-Specjal.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/Yulia-Deyneka-by-Zuzana-Specjal.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-03-28T10:23:50+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-04-30T16:34:55+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/festivalcapuchos\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Yulia Deyneka - Festival de M\u00fasica dos Capuchos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Nascida na R\u00fassia, em 1982, Yulia Deyneka estudou com Alexander Bobrovsky no Conservat\u00f3rio Tchaikovsky da sua cidade natal, Moscovo. Em 2001, mudou-se para a Alemanha, onde se diplomou pela Universidade de M\u00fasica e Teatro de Rostock, sob a orienta\u00e7\u00e3o de Felix Schwartz, tendo posteriormente obtido o Diploma de Solista na Universidade das Artes de Berlim,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/GERAL-1X1-REDES.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/artista\\\/yulia-deyneka\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/category\\\/o-festival\\\/#listItem\",\"name\":\"O Festival\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/category\\\/o-festival\\\/#listItem\",\"position\":2,\"name\":\"O Festival\",\"item\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/category\\\/o-festival\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/category\\\/o-festival\\\/programa-geral\\\/#listItem\",\"name\":\"Programa Geral\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/category\\\/o-festival\\\/programa-geral\\\/#listItem\",\"position\":3,\"name\":\"Programa Geral\",\"item\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/category\\\/o-festival\\\/programa-geral\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/category\\\/o-festival\\\/programa-geral\\\/20-junho\\\/#listItem\",\"name\":\"20 JUNHO\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/category\\\/o-festival\\\/#listItem\",\"name\":\"O Festival\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/category\\\/o-festival\\\/programa-geral\\\/20-junho\\\/#listItem\",\"position\":4,\"name\":\"20 JUNHO\",\"item\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/category\\\/o-festival\\\/programa-geral\\\/20-junho\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/artista\\\/yulia-deyneka\\\/#listItem\",\"name\":\"Yulia Deyneka\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/category\\\/o-festival\\\/programa-geral\\\/#listItem\",\"name\":\"Programa Geral\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/artista\\\/yulia-deyneka\\\/#listItem\",\"position\":5,\"name\":\"Yulia Deyneka\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/category\\\/o-festival\\\/programa-geral\\\/20-junho\\\/#listItem\",\"name\":\"20 JUNHO\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/#organization\",\"name\":\"Festival de M\\u00fasica dos Capuchos\",\"description\":\"Official site\",\"url\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/festivalcapuchos.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Flavicon-Capuchos-2025.png\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/artista\\\/yulia-deyneka\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/artista\\\/yulia-deyneka\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/festivalcapuchos\",\"https:\\\/\\\/instagram.com\\\/festivalcapuchos\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/artista\\\/yulia-deyneka\\\/#webpage\",\"url\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/artista\\\/yulia-deyneka\\\/\",\"name\":\"Yulia Deyneka - Festival de M\\u00fasica dos Capuchos\",\"description\":\"Nascida na R\\u00fassia, em 1982, Yulia Deyneka estudou com Alexander Bobrovsky no Conservat\\u00f3rio Tchaikovsky da sua cidade natal, Moscovo. Em 2001, mudou-se para a Alemanha, onde se diplomou pela Universidade de M\\u00fasica e Teatro de Rostock, sob a orienta\\u00e7\\u00e3o de Felix Schwartz, tendo posteriormente obtido o Diploma de Solista na Universidade das Artes de Berlim,\",\"inLanguage\":\"pt-PT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/artista\\\/yulia-deyneka\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Yulia-Deyneka-by-Zuzana-Specjal.jpg\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/artista\\\/yulia-deyneka\\\/#mainImage\",\"width\":1280,\"height\":1280,\"caption\":\"\\u00a9 Zuzana Specjal\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/artista\\\/yulia-deyneka\\\/#mainImage\"},\"datePublished\":\"2025-03-28T10:23:50+00:00\",\"dateModified\":\"2025-04-30T17:34:55+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/\",\"name\":\"Festival de M\\u00fasica dos Capuchos\",\"description\":\"Official site\",\"inLanguage\":\"pt-PT\",\"publisher\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Yulia Deyneka - Festival de M\u00fasica dos Capuchos","description":"Nascida na R\u00fassia, em 1982, Yulia Deyneka estudou com Alexander Bobrovsky no Conservat\u00f3rio Tchaikovsky da sua cidade natal, Moscovo. Em 2001, mudou-se para a Alemanha, onde se diplomou pela Universidade de M\u00fasica e Teatro de Rostock, sob a orienta\u00e7\u00e3o de Felix Schwartz, tendo posteriormente obtido o Diploma de Solista na Universidade das Artes de Berlim,","canonical_url":"https:\/\/lab.festivalcapuchos.com\/pt\/artista\/yulia-deyneka\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"sy1uYlrwItWeoGZgdRBBrgERAURdM1NZLTjfn6Ou-sw","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/artista\/yulia-deyneka\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt#listItem","position":1,"name":"Home","item":"https:\/\/lab.festivalcapuchos.com\/pt","nextItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/o-festival\/#listItem","name":"O Festival"}},{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/o-festival\/#listItem","position":2,"name":"O Festival","item":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/o-festival\/","nextItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/o-festival\/programa-geral\/#listItem","name":"Programa Geral"},"previousItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/o-festival\/programa-geral\/#listItem","position":3,"name":"Programa Geral","item":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/o-festival\/programa-geral\/","nextItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/o-festival\/programa-geral\/20-junho\/#listItem","name":"20 JUNHO"},"previousItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/o-festival\/#listItem","name":"O Festival"}},{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/o-festival\/programa-geral\/20-junho\/#listItem","position":4,"name":"20 JUNHO","item":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/o-festival\/programa-geral\/20-junho\/","nextItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/artista\/yulia-deyneka\/#listItem","name":"Yulia Deyneka"},"previousItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/o-festival\/programa-geral\/#listItem","name":"Programa Geral"}},{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/artista\/yulia-deyneka\/#listItem","position":5,"name":"Yulia Deyneka","previousItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/o-festival\/programa-geral\/20-junho\/#listItem","name":"20 JUNHO"}}]},{"@type":"Organization","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/#organization","name":"Festival de M\u00fasica dos Capuchos","description":"Official site","url":"https:\/\/lab.festivalcapuchos.com\/pt\/","logo":{"@type":"ImageObject","url":"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/Flavicon-Capuchos-2025.png","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/artista\/yulia-deyneka\/#organizationLogo"},"image":{"@id":"https:\/\/lab.festivalcapuchos.com\/pt\/artista\/yulia-deyneka\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/festivalcapuchos","https:\/\/instagram.com\/festivalcapuchos"]},{"@type":"WebPage","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/artista\/yulia-deyneka\/#webpage","url":"https:\/\/lab.festivalcapuchos.com\/pt\/artista\/yulia-deyneka\/","name":"Yulia Deyneka - Festival de M\u00fasica dos Capuchos","description":"Nascida na R\u00fassia, em 1982, Yulia Deyneka estudou com Alexander Bobrovsky no Conservat\u00f3rio Tchaikovsky da sua cidade natal, Moscovo. Em 2001, mudou-se para a Alemanha, onde se diplomou pela Universidade de M\u00fasica e Teatro de Rostock, sob a orienta\u00e7\u00e3o de Felix Schwartz, tendo posteriormente obtido o Diploma de Solista na Universidade das Artes de Berlim,","inLanguage":"pt-PT","isPartOf":{"@id":"https:\/\/lab.festivalcapuchos.com\/pt\/#website"},"breadcrumb":{"@id":"https:\/\/lab.festivalcapuchos.com\/pt\/artista\/yulia-deyneka\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/lab.festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/Yulia-Deyneka-by-Zuzana-Specjal.jpg","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/artista\/yulia-deyneka\/#mainImage","width":1280,"height":1280,"caption":"\u00a9 Zuzana Specjal"},"primaryImageOfPage":{"@id":"https:\/\/lab.festivalcapuchos.com\/pt\/artista\/yulia-deyneka\/#mainImage"},"datePublished":"2025-03-28T10:23:50+00:00","dateModified":"2025-04-30T17:34:55+01:00"},{"@type":"WebSite","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/#website","url":"https:\/\/lab.festivalcapuchos.com\/pt\/","name":"Festival de M\u00fasica dos Capuchos","description":"Official site","inLanguage":"pt-PT","publisher":{"@id":"https:\/\/lab.festivalcapuchos.com\/pt\/#organization"}}]},"og:locale":"pt_PT","og:site_name":"Festival de M\u00fasica dos Capuchos - Official site","og:type":"article","og:title":"Yulia Deyneka - Festival de M\u00fasica dos Capuchos","og:description":"Nascida na R\u00fassia, em 1982, Yulia Deyneka estudou com Alexander Bobrovsky no Conservat\u00f3rio Tchaikovsky da sua cidade natal, Moscovo. Em 2001, mudou-se para a Alemanha, onde se diplomou pela Universidade de M\u00fasica e Teatro de Rostock, sob a orienta\u00e7\u00e3o de Felix Schwartz, tendo posteriormente obtido o Diploma de Solista na Universidade das Artes de Berlim,","og:url":"https:\/\/lab.festivalcapuchos.com\/pt\/artista\/yulia-deyneka\/","og:image":"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/Yulia-Deyneka-by-Zuzana-Specjal.jpg","og:image:secure_url":"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/Yulia-Deyneka-by-Zuzana-Specjal.jpg","og:image:width":"1280","og:image:height":"1280","article:published_time":"2025-03-28T10:23:50+00:00","article:modified_time":"2025-04-30T16:34:55+00:00","article:publisher":"https:\/\/facebook.com\/festivalcapuchos","twitter:card":"summary","twitter:title":"Yulia Deyneka - Festival de M\u00fasica dos Capuchos","twitter:description":"Nascida na R\u00fassia, em 1982, Yulia Deyneka estudou com Alexander Bobrovsky no Conservat\u00f3rio Tchaikovsky da sua cidade natal, Moscovo. Em 2001, mudou-se para a Alemanha, onde se diplomou pela Universidade de M\u00fasica e Teatro de Rostock, sob a orienta\u00e7\u00e3o de Felix Schwartz, tendo posteriormente obtido o Diploma de Solista na Universidade das Artes de Berlim,","twitter:image":"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/GERAL-1X1-REDES.jpg"},"aioseo_meta_data":{"post_id":"16855","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"featured","og_image_url":"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/Yulia-Deyneka-by-Zuzana-Specjal.jpg","og_image_width":"1280","og_image_height":"1280","og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":"","og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":0,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-03-28 10:20:22","updated":"2025-06-04 00:02:03","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lab.festivalcapuchos.com\/pt\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lab.festivalcapuchos.com\/pt\/category\/o-festival\/\" title=\"O Festival\">O Festival<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lab.festivalcapuchos.com\/pt\/category\/o-festival\/programa-geral\/\" title=\"Programa Geral\">Programa Geral<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lab.festivalcapuchos.com\/pt\/category\/o-festival\/programa-geral\/20-junho\/\" title=\"20 JUNHO\">20 JUNHO<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tYulia Deyneka\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/lab.festivalcapuchos.com\/pt"},{"label":"O Festival","link":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/o-festival\/"},{"label":"Programa Geral","link":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/o-festival\/programa-geral\/"},{"label":"20 JUNHO","link":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/o-festival\/programa-geral\/20-junho\/"},{"label":"Yulia Deyneka","link":"https:\/\/lab.festivalcapuchos.com\/pt\/artista\/yulia-deyneka\/"}],"_links":{"self":[{"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/artista\/16855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/artista"}],"about":[{"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/types\/artista"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/media\/16160"}],"wp:attachment":[{"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/media?parent=16855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/categories?post=16855"},{"taxonomy":"ano","embeddable":true,"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/ano?post=16855"},{"taxonomy":"com-pagina","embeddable":true,"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/com-pagina?post=16855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}