{"id":15710,"date":"2024-04-20T19:50:21","date_gmt":"2024-04-20T18:50:21","guid":{"rendered":"https:\/\/festivalcapuchos.com\/?p=15710"},"modified":"2025-04-03T11:31:35","modified_gmt":"2025-04-03T10:31:35","slug":"festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho","status":"publish","type":"post","link":"https:\/\/lab.festivalcapuchos.com\/pt\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\/","title":{"rendered":"Festival dos Capuchos celebra as conquistas de Abril entre Maio e Junho"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":15785,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ocean_front_end_style_editor":"no","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[62,43],"tags":[],"ano":[16],"concerto-com-pagina":[],"class_list":["post-15710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-imprensa","category-na-imprensa","ano-16","entry","has-media"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Leonor Coelho\"\/>\n\t<meta name=\"google-site-verification\" content=\"sy1uYlrwItWeoGZgdRBBrgERAURdM1NZLTjfn6Ou-sw\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/lab.festivalcapuchos.com\/pt\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_PT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Festival de M\u00fasica dos Capuchos - Official site\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Festival dos Capuchos celebra as conquistas de Abril entre Maio e Junho - Festival de M\u00fasica dos Capuchos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/lab.festivalcapuchos.com\/pt\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/GERAL-1X1-REDES.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/GERAL-1X1-REDES.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-04-20T18:50:21+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-04-03T10:31:35+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/festivalcapuchos\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Festival dos Capuchos celebra as conquistas de Abril entre Maio e Junho - Festival de M\u00fasica dos Capuchos\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/GERAL-1X1-REDES.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\\\/#blogposting\",\"name\":\"Festival dos Capuchos celebra as conquistas de Abril entre Maio e Junho - Festival de M\\u00fasica dos Capuchos\",\"headline\":\"Festival dos Capuchos celebra as conquistas de Abril entre Maio e Junho\",\"author\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/author\\\/lc\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/TIMEOUT.jpg\",\"width\":1400,\"height\":1400},\"datePublished\":\"2024-04-20T19:50:21+01:00\",\"dateModified\":\"2025-04-03T11:31:35+01:00\",\"inLanguage\":\"pt-PT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\\\/#webpage\"},\"articleSection\":\"Imprensa, Na Imprensa, 2024\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/category\\\/imprensa\\\/#listItem\",\"name\":\"Imprensa\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/category\\\/imprensa\\\/#listItem\",\"position\":2,\"name\":\"Imprensa\",\"item\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/category\\\/imprensa\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/category\\\/imprensa\\\/na-imprensa\\\/#listItem\",\"name\":\"Na Imprensa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/category\\\/imprensa\\\/na-imprensa\\\/#listItem\",\"position\":3,\"name\":\"Na Imprensa\",\"item\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/category\\\/imprensa\\\/na-imprensa\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\\\/#listItem\",\"name\":\"Festival dos Capuchos celebra as conquistas de Abril entre Maio e Junho\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/category\\\/imprensa\\\/#listItem\",\"name\":\"Imprensa\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\\\/#listItem\",\"position\":4,\"name\":\"Festival dos Capuchos celebra as conquistas de Abril entre Maio e Junho\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/category\\\/imprensa\\\/na-imprensa\\\/#listItem\",\"name\":\"Na Imprensa\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/#organization\",\"name\":\"Festival de M\\u00fasica dos Capuchos\",\"description\":\"Official site\",\"url\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/festivalcapuchos.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Flavicon-Capuchos-2025.png\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/festivalcapuchos\",\"https:\\\/\\\/instagram.com\\\/festivalcapuchos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/author\\\/lc\\\/#author\",\"url\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/author\\\/lc\\\/\",\"name\":\"Leonor Coelho\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a81694bf3195b9d56626668fbc53d66907632d503a70daa606962cee2ac17ea0?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Leonor Coelho\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\\\/#webpage\",\"url\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\\\/\",\"name\":\"Festival dos Capuchos celebra as conquistas de Abril entre Maio e Junho - Festival de M\\u00fasica dos Capuchos\",\"inLanguage\":\"pt-PT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/author\\\/lc\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/author\\\/lc\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/TIMEOUT.jpg\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\\\/#mainImage\",\"width\":1400,\"height\":1400},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\\\/#mainImage\"},\"datePublished\":\"2024-04-20T19:50:21+01:00\",\"dateModified\":\"2025-04-03T11:31:35+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/\",\"name\":\"Festival de M\\u00fasica dos Capuchos\",\"description\":\"Official site\",\"inLanguage\":\"pt-PT\",\"publisher\":{\"@id\":\"https:\\\/\\\/lab.festivalcapuchos.com\\\/pt\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Festival dos Capuchos celebra as conquistas de Abril entre Maio e Junho - Festival de M\u00fasica dos Capuchos","description":"","canonical_url":"https:\/\/lab.festivalcapuchos.com\/pt\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"sy1uYlrwItWeoGZgdRBBrgERAURdM1NZLTjfn6Ou-sw","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\/#blogposting","name":"Festival dos Capuchos celebra as conquistas de Abril entre Maio e Junho - Festival de M\u00fasica dos Capuchos","headline":"Festival dos Capuchos celebra as conquistas de Abril entre Maio e Junho","author":{"@id":"https:\/\/lab.festivalcapuchos.com\/pt\/author\/lc\/#author"},"publisher":{"@id":"https:\/\/lab.festivalcapuchos.com\/pt\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/lab.festivalcapuchos.com\/wp-content\/uploads\/2024\/04\/TIMEOUT.jpg","width":1400,"height":1400},"datePublished":"2024-04-20T19:50:21+01:00","dateModified":"2025-04-03T11:31:35+01:00","inLanguage":"pt-PT","mainEntityOfPage":{"@id":"https:\/\/lab.festivalcapuchos.com\/pt\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\/#webpage"},"isPartOf":{"@id":"https:\/\/lab.festivalcapuchos.com\/pt\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\/#webpage"},"articleSection":"Imprensa, Na Imprensa, 2024"},{"@type":"BreadcrumbList","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt#listItem","position":1,"name":"Home","item":"https:\/\/lab.festivalcapuchos.com\/pt","nextItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/imprensa\/#listItem","name":"Imprensa"}},{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/imprensa\/#listItem","position":2,"name":"Imprensa","item":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/imprensa\/","nextItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/imprensa\/na-imprensa\/#listItem","name":"Na Imprensa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/imprensa\/na-imprensa\/#listItem","position":3,"name":"Na Imprensa","item":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/imprensa\/na-imprensa\/","nextItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\/#listItem","name":"Festival dos Capuchos celebra as conquistas de Abril entre Maio e Junho"},"previousItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/imprensa\/#listItem","name":"Imprensa"}},{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\/#listItem","position":4,"name":"Festival dos Capuchos celebra as conquistas de Abril entre Maio e Junho","previousItem":{"@type":"ListItem","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/imprensa\/na-imprensa\/#listItem","name":"Na Imprensa"}}]},{"@type":"Organization","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/#organization","name":"Festival de M\u00fasica dos Capuchos","description":"Official site","url":"https:\/\/lab.festivalcapuchos.com\/pt\/","logo":{"@type":"ImageObject","url":"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/Flavicon-Capuchos-2025.png","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\/#organizationLogo"},"image":{"@id":"https:\/\/lab.festivalcapuchos.com\/pt\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/festivalcapuchos","https:\/\/instagram.com\/festivalcapuchos"]},{"@type":"Person","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/author\/lc\/#author","url":"https:\/\/lab.festivalcapuchos.com\/pt\/author\/lc\/","name":"Leonor Coelho","image":{"@type":"ImageObject","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a81694bf3195b9d56626668fbc53d66907632d503a70daa606962cee2ac17ea0?s=96&d=mm&r=g","width":96,"height":96,"caption":"Leonor Coelho"}},{"@type":"WebPage","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\/#webpage","url":"https:\/\/lab.festivalcapuchos.com\/pt\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\/","name":"Festival dos Capuchos celebra as conquistas de Abril entre Maio e Junho - Festival de M\u00fasica dos Capuchos","inLanguage":"pt-PT","isPartOf":{"@id":"https:\/\/lab.festivalcapuchos.com\/pt\/#website"},"breadcrumb":{"@id":"https:\/\/lab.festivalcapuchos.com\/pt\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\/#breadcrumblist"},"author":{"@id":"https:\/\/lab.festivalcapuchos.com\/pt\/author\/lc\/#author"},"creator":{"@id":"https:\/\/lab.festivalcapuchos.com\/pt\/author\/lc\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/lab.festivalcapuchos.com\/wp-content\/uploads\/2024\/04\/TIMEOUT.jpg","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\/#mainImage","width":1400,"height":1400},"primaryImageOfPage":{"@id":"https:\/\/lab.festivalcapuchos.com\/pt\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\/#mainImage"},"datePublished":"2024-04-20T19:50:21+01:00","dateModified":"2025-04-03T11:31:35+01:00"},{"@type":"WebSite","@id":"https:\/\/lab.festivalcapuchos.com\/pt\/#website","url":"https:\/\/lab.festivalcapuchos.com\/pt\/","name":"Festival de M\u00fasica dos Capuchos","description":"Official site","inLanguage":"pt-PT","publisher":{"@id":"https:\/\/lab.festivalcapuchos.com\/pt\/#organization"}}]},"og:locale":"pt_PT","og:site_name":"Festival de M\u00fasica dos Capuchos - Official site","og:type":"article","og:title":"Festival dos Capuchos celebra as conquistas de Abril entre Maio e Junho - Festival de M\u00fasica dos Capuchos","og:url":"https:\/\/lab.festivalcapuchos.com\/pt\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\/","og:image":"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/GERAL-1X1-REDES.jpg","og:image:secure_url":"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/GERAL-1X1-REDES.jpg","article:published_time":"2024-04-20T18:50:21+00:00","article:modified_time":"2025-04-03T10:31:35+00:00","article:publisher":"https:\/\/facebook.com\/festivalcapuchos","twitter:card":"summary","twitter:title":"Festival dos Capuchos celebra as conquistas de Abril entre Maio e Junho - Festival de M\u00fasica dos Capuchos","twitter:image":"https:\/\/festivalcapuchos.com\/wp-content\/uploads\/2025\/03\/GERAL-1X1-REDES.jpg"},"aioseo_meta_data":{"post_id":"15710","title":"","description":"","keywords":"","keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":"","canonical_url":"","og_title":"","og_description":"","og_object_type":"default","og_image_type":"default","og_image_url":"","og_image_width":"0","og_image_height":"0","og_image_custom_url":"","og_image_custom_fields":"","og_video":"","og_custom_url":"","og_article_section":"","og_article_tags":"","twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":"","twitter_image_custom_url":"","twitter_image_custom_fields":"","twitter_title":"","twitter_description":"","schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":0,"frequency":"default","local_seo":"","breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-04-16 09:50:23","updated":"2025-06-04 02:12:26","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lab.festivalcapuchos.com\/pt\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lab.festivalcapuchos.com\/pt\/category\/imprensa\/\" title=\"Imprensa\">Imprensa<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lab.festivalcapuchos.com\/pt\/category\/imprensa\/na-imprensa\/\" title=\"Na Imprensa\">Na Imprensa<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tFestival dos Capuchos celebra as conquistas de Abril entre Maio e Junho\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/lab.festivalcapuchos.com\/pt"},{"label":"Imprensa","link":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/imprensa\/"},{"label":"Na Imprensa","link":"https:\/\/lab.festivalcapuchos.com\/pt\/category\/imprensa\/na-imprensa\/"},{"label":"Festival dos Capuchos celebra as conquistas de Abril entre Maio e Junho","link":"https:\/\/lab.festivalcapuchos.com\/pt\/festival-dos-capuchos-celebra-as-conquistas-de-abril-entre-maio-e-junho\/"}],"_links":{"self":[{"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/posts\/15710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/comments?post=15710"}],"version-history":[{"count":7,"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/posts\/15710\/revisions"}],"predecessor-version":[{"id":15755,"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/posts\/15710\/revisions\/15755"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/media\/15785"}],"wp:attachment":[{"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/media?parent=15710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/categories?post=15710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/tags?post=15710"},{"taxonomy":"ano","embeddable":true,"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/ano?post=15710"},{"taxonomy":"concerto-com-pagina","embeddable":true,"href":"https:\/\/lab.festivalcapuchos.com\/pt\/wp-json\/wp\/v2\/concerto-com-pagina?post=15710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}